{"id":2869,"date":"2020-04-21T17:50:11","date_gmt":"2020-04-21T17:50:11","guid":{"rendered":"http:\/\/cristianocarvalho.net\/WordPress\/?post_type=product&#038;p=2869"},"modified":"2021-12-23T19:27:08","modified_gmt":"2021-12-23T19:27:08","slug":"detector-mov-220o-rf-knx-solar-antracite-tre531","status":"publish","type":"product","link":"https:\/\/cristianocarvalho.net\/WordPress\/produto\/detector-mov-220o-rf-knx-solar-antracite-tre531\/","title":{"rendered":"Detector mov. 220\u00ba RF KNX solar antracite &#8211; TRE531"},"content":{"rendered":"<h2 class=\"big\">Detector mov. 220\u00ba RF KNX solar antracite &#8211; TRE531<\/h2>\n<p>Detectores de movimento 220\u00b0 IP55 RF KNX, solar, antracite.<\/p>\n<p><strong>Fun\u00e7\u00f5es:<\/strong><\/p>\n<ul>\n<li>Funcionamento comandado por microprocessador.<\/li>\n<li>ETS fun\u00e7\u00f5es adicionais: modo de opera\u00e7\u00e3o ligado \/ desligado, bot\u00e3o de press\u00e3o, regul\u00e1vel, exibi\u00e7\u00e3o de brilho, carregamento da cena do movimento, sem carga de movimento.<\/li>\n<li>Fun\u00e7\u00e3o de reset (de acordo com defini\u00e7\u00e3o de f\u00e1brica).<\/li>\n<li>Fun\u00e7\u00f5es de quicklink: tempo de comuta\u00e7\u00e3o, bot\u00e3o de contacto NO.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/www.hager.pt\/files\/download\/0\/683831_1\/0\/Ficha%20t%C3%A9cnica%20TRE531.pdf\">Ficha t\u00e9cnica do produto &#8211; pdf<\/a><\/p>\n<p>Detectores de movimento 220\u00b0 IP55 RF KNX, solar, antracite.<\/p>\n<p><strong>Pre\u00e7o sem IVA<br \/>\n<span style=\"color: #fc5f3f;\">Custos de expedi\u00e7\u00e3o calculado s\u00f3 para Portugal Continental.<\/span><\/strong><\/p>\n","protected":false},"featured_media":2870,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[53,55,54],"product_tag":[],"class_list":{"0":"post-2869","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hager-coviva","7":"product_cat-hager-easy","8":"product_cat-hager-knx","9":"product_shipping_class-preco-inferior-a-30kg-em-portugal","11":"first","12":"onbackorder","13":"sale","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/comments?post=2869"}],"version-history":[{"count":2,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2869\/revisions"}],"predecessor-version":[{"id":2875,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2869\/revisions\/2875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/media?parent=2869"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_brand?post=2869"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_cat?post=2869"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_tag?post=2869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}