{"id":2854,"date":"2020-04-21T17:19:59","date_gmt":"2020-04-21T17:19:59","guid":{"rendered":"http:\/\/cristianocarvalho.net\/WordPress\/?post_type=product&#038;p=2854"},"modified":"2021-12-23T19:08:15","modified_gmt":"2021-12-23T19:08:15","slug":"bp-2-canal-rf-knx-ip55-tre302","status":"publish","type":"product","link":"https:\/\/cristianocarvalho.net\/WordPress\/produto\/bp-2-canal-rf-knx-ip55-tre302\/","title":{"rendered":"BP 2 canal RF KNX IP55 &#8211; TRE302"},"content":{"rendered":"<h2 class=\"big\">BP 2 canal RF KNX IP55 &#8211; TRE302<\/h2>\n<p>2 tecla<br \/>\nalimenta\u00e7\u00e3o: 2x CR2430 3,0V<\/p>\n<p><strong>Fun\u00e7\u00f5es:<\/strong><\/p>\n<ul>\n<li>ETS fun\u00e7\u00f5es adicionais: +6 cenas, modo de opera\u00e7\u00e3o on \/ off, 1 controle de bot\u00e3o para cima \/ para baixo, bot\u00e3o, 2 x alarme, exibi\u00e7\u00e3o de status.<\/li>\n<li>Fun\u00e7\u00e3o de reset (de acordo com defini\u00e7\u00e3o de f\u00e1brica).<\/li>\n<li>Fun\u00e7\u00f5es de quicklink: comuta\u00e7\u00e3o, regul\u00e1vel, 2 cenas, tempo de comuta\u00e7\u00e3o, bot\u00e3o de press\u00e3o, contacto NO.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><a href=\"https:\/\/www.hager.pt\/files\/download\/0\/685752_1\/0\/Ficha%20t%C3%A9cnica%20TRE302.pdf\">Ficha t\u00e9cnica do produto &#8211; pdf<\/a><\/p>\n<p>Bot\u00e3o de press\u00e3o IP55 RF KNX<\/p>\n<p><strong>Pre\u00e7o sem IVA<br \/>\n<span style=\"color: #fc5f3f;\">Custos de expedi\u00e7\u00e3o calculado s\u00f3 para Portugal Continental.<\/span><\/strong><\/p>\n","protected":false},"featured_media":2866,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[53,55,54],"product_tag":[],"class_list":{"0":"post-2854","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-hager-coviva","7":"product_cat-hager-easy","8":"product_cat-hager-knx","9":"product_shipping_class-preco-inferior-a-30kg-em-portugal","11":"first","12":"onbackorder","13":"sale","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/comments?post=2854"}],"version-history":[{"count":1,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2854\/revisions"}],"predecessor-version":[{"id":2856,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product\/2854\/revisions\/2856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/media\/2866"}],"wp:attachment":[{"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/media?parent=2854"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_brand?post=2854"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_cat?post=2854"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cristianocarvalho.net\/WordPress\/wp-json\/wp\/v2\/product_tag?post=2854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}